{"id":91557,"date":"2024-11-29T11:14:09","date_gmt":"2024-11-29T11:14:09","guid":{"rendered":"https:\/\/www.internationalmindfulnessconference.com\/?post_type=eb_course&#038;p=91557"},"modified":"2024-12-10T08:56:13","modified_gmt":"2024-12-10T08:56:13","slug":"icm2024-%ce%b9%cf%83%cf%80%ce%b1%ce%bd%ce%b9%ce%ba%cf%8c%cf%82-%ce%ba%cf%8c%ce%bc%ce%b2%ce%bf%cf%82","status":"publish","type":"eb_course","link":"https:\/\/www.internationalmindfulnessconference.com\/el\/%ce%bc%ce%b1%ce%b8%ce%ae%ce%bc%ce%b1%cf%84%ce%b1\/icm2024-%ce%b9%cf%83%cf%80%ce%b1%ce%bd%ce%b9%ce%ba%cf%8c%cf%82-%ce%ba%cf%8c%ce%bc%ce%b2%ce%bf%cf%82\/","title":{"rendered":"ICM:2024 \u0399\u03c3\u03c0\u03b1\u03bd\u03b9\u03ba\u03ac HUB"},"content":{"rendered":"","protected":false},"featured_media":94912,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_view_id":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"wds_primary_eb_course_cat":0},"eb_course_cat":[167],"class_list":["post-91557","eb_course","type-eb_course","status-publish","has-post-thumbnail","hentry","eb_course_cat-welcometoicm2024communityportal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ICM:2024 Spanish HUB - International Conference on Mindfulness 2024<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ICM:2024 Spanish HUB - International Conference on Mindfulness 2024\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.internationalmindfulnessconference.com\/el\/\u03bc\u03b1\u03b8\u03ae\u03bc\u03b1\u03c4\u03b1\/icm2024-\u03b9\u03c3\u03c0\u03b1\u03bd\u03b9\u03ba\u03cc\u03c2-\u03ba\u03cc\u03bc\u03b2\u03bf\u03c2\/\" \/>\n<meta property=\"og:site_name\" content=\"International Conference on Mindfulness 2024\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MindfulnessNetworkUK\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-10T08:56:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.internationalmindfulnessconference.com\/wp-content\/uploads\/2024\/11\/Spain-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MindfulnessN\" \/>\n<meta name=\"twitter:label1\" content=\"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u03bb\u03b5\u03c0\u03c4\u03cc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/icm2024-spanish-hub\\\/\",\"url\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/icm2024-spanish-hub\\\/\",\"name\":\"ICM:2024 Spanish HUB - International Conference on Mindfulness 2024\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/icm2024-spanish-hub\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/icm2024-spanish-hub\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Spain-1.png\",\"datePublished\":\"2024-11-29T11:14:09+00:00\",\"dateModified\":\"2024-12-10T08:56:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/icm2024-spanish-hub\\\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/icm2024-spanish-hub\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/icm2024-spanish-hub\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Spain-1.png\",\"contentUrl\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Spain-1.png\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/icm2024-spanish-hub\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Course\",\"item\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ICM:2024 Spanish HUB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/#website\",\"url\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/\",\"name\":\"International Conference on Mindfulness 2024\",\"description\":\"ICM 2024: Mindfulness in a Changing World\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/#organization\"},\"alternateName\":\"ICM 2024\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/#organization\",\"name\":\"The Mindfulness Network\",\"alternateName\":\"Mindfulness Network\",\"url\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/MNLogo-300x300-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/MNLogo-300x300-1.jpg\",\"width\":300,\"height\":300,\"caption\":\"The Mindfulness Network\"},\"image\":{\"@id\":\"https:\\\/\\\/www.internationalmindfulnessconference.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MindfulnessNetworkUK\\\/\",\"https:\\\/\\\/x.com\\\/MindfulnessN\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ICM:2024 \u0399\u03c3\u03c0\u03b1\u03bd\u03b9\u03ba\u03cc HUB - \u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a3\u03c5\u03bd\u03ad\u03b4\u03c1\u03b9\u03bf \u03b3\u03b9\u03b1 \u03c4\u03b7\u03bd \u0395\u03bd\u03c3\u03c5\u03bd\u03b5\u03b9\u03b4\u03b7\u03c4\u03cc\u03c4\u03b7\u03c4\u03b1 2024","robots":{"index":"noindex","follow":"follow"},"og_locale":"el_GR","og_type":"article","og_title":"ICM:2024 Spanish HUB - International Conference on Mindfulness 2024","og_url":"https:\/\/www.internationalmindfulnessconference.com\/el\/\u03bc\u03b1\u03b8\u03ae\u03bc\u03b1\u03c4\u03b1\/icm2024-\u03b9\u03c3\u03c0\u03b1\u03bd\u03b9\u03ba\u03cc\u03c2-\u03ba\u03cc\u03bc\u03b2\u03bf\u03c2\/","og_site_name":"International Conference on Mindfulness 2024","article_publisher":"https:\/\/www.facebook.com\/MindfulnessNetworkUK\/","article_modified_time":"2024-12-10T08:56:13+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.internationalmindfulnessconference.com\/wp-content\/uploads\/2024\/11\/Spain-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@MindfulnessN","twitter_misc":{"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2":"1 \u03bb\u03b5\u03c0\u03c4\u03cc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.internationalmindfulnessconference.com\/courses\/icm2024-spanish-hub\/","url":"https:\/\/www.internationalmindfulnessconference.com\/courses\/icm2024-spanish-hub\/","name":"ICM:2024 \u0399\u03c3\u03c0\u03b1\u03bd\u03b9\u03ba\u03cc HUB - \u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03a3\u03c5\u03bd\u03ad\u03b4\u03c1\u03b9\u03bf \u03b3\u03b9\u03b1 \u03c4\u03b7\u03bd \u0395\u03bd\u03c3\u03c5\u03bd\u03b5\u03b9\u03b4\u03b7\u03c4\u03cc\u03c4\u03b7\u03c4\u03b1 2024","isPartOf":{"@id":"https:\/\/www.internationalmindfulnessconference.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.internationalmindfulnessconference.com\/courses\/icm2024-spanish-hub\/#primaryimage"},"image":{"@id":"https:\/\/www.internationalmindfulnessconference.com\/courses\/icm2024-spanish-hub\/#primaryimage"},"thumbnailUrl":"https:\/\/www.internationalmindfulnessconference.com\/wp-content\/uploads\/2024\/11\/Spain-1.png","datePublished":"2024-11-29T11:14:09+00:00","dateModified":"2024-12-10T08:56:13+00:00","breadcrumb":{"@id":"https:\/\/www.internationalmindfulnessconference.com\/courses\/icm2024-spanish-hub\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.internationalmindfulnessconference.com\/courses\/icm2024-spanish-hub\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.internationalmindfulnessconference.com\/courses\/icm2024-spanish-hub\/#primaryimage","url":"https:\/\/www.internationalmindfulnessconference.com\/wp-content\/uploads\/2024\/11\/Spain-1.png","contentUrl":"https:\/\/www.internationalmindfulnessconference.com\/wp-content\/uploads\/2024\/11\/Spain-1.png","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.internationalmindfulnessconference.com\/courses\/icm2024-spanish-hub\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.internationalmindfulnessconference.com\/"},{"@type":"ListItem","position":2,"name":"Course","item":"https:\/\/www.internationalmindfulnessconference.com\/courses\/"},{"@type":"ListItem","position":3,"name":"ICM:2024 Spanish HUB"}]},{"@type":"WebSite","@id":"https:\/\/www.internationalmindfulnessconference.com\/#website","url":"https:\/\/www.internationalmindfulnessconference.com\/","name":"\u0394\u03b9\u03b5\u03b8\u03bd\u03ad\u03c2 \u03c3\u03c5\u03bd\u03ad\u03b4\u03c1\u03b9\u03bf \u03b3\u03b9\u03b1 \u03c4\u03b7\u03bd \u03b5\u03bd\u03c3\u03c5\u03bd\u03b5\u03b9\u03b4\u03b7\u03c4\u03cc\u03c4\u03b7\u03c4\u03b1 2024","description":"ICM 2024: Mindfulness in a Changing World","publisher":{"@id":"https:\/\/www.internationalmindfulnessconference.com\/#organization"},"alternateName":"ICM 2024","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.internationalmindfulnessconference.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/www.internationalmindfulnessconference.com\/#organization","name":"\u03a4\u03bf \u03b4\u03af\u03ba\u03c4\u03c5\u03bf Mindfulness Network","alternateName":"Mindfulness Network","url":"https:\/\/www.internationalmindfulnessconference.com\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.internationalmindfulnessconference.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.internationalmindfulnessconference.com\/wp-content\/uploads\/2023\/01\/MNLogo-300x300-1.jpg","contentUrl":"https:\/\/www.internationalmindfulnessconference.com\/wp-content\/uploads\/2023\/01\/MNLogo-300x300-1.jpg","width":300,"height":300,"caption":"The Mindfulness Network"},"image":{"@id":"https:\/\/www.internationalmindfulnessconference.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MindfulnessNetworkUK\/","https:\/\/x.com\/MindfulnessN"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.internationalmindfulnessconference.com\/el\/wp-json\/wp\/v2\/eb_course\/91557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.internationalmindfulnessconference.com\/el\/wp-json\/wp\/v2\/eb_course"}],"about":[{"href":"https:\/\/www.internationalmindfulnessconference.com\/el\/wp-json\/wp\/v2\/types\/eb_course"}],"replies":[{"embeddable":true,"href":"https:\/\/www.internationalmindfulnessconference.com\/el\/wp-json\/wp\/v2\/comments?post=91557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.internationalmindfulnessconference.com\/el\/wp-json\/wp\/v2\/media\/94912"}],"wp:attachment":[{"href":"https:\/\/www.internationalmindfulnessconference.com\/el\/wp-json\/wp\/v2\/media?parent=91557"}],"wp:term":[{"taxonomy":"eb_course_cat","embeddable":true,"href":"https:\/\/www.internationalmindfulnessconference.com\/el\/wp-json\/wp\/v2\/eb_course_cat?post=91557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}